{"id":12873,"date":"2013-12-09T13:49:00","date_gmt":"2013-12-09T12:49:00","guid":{"rendered":"http:\/\/theark.ch\/techno-pole-de-sierre-visite-de-la-cite-interdite-1008\/"},"modified":"2013-12-09T13:49:00","modified_gmt":"2013-12-09T11:49:00","slug":"techno-pole-de-sierre-visite-de-la-cite-interdite-1008","status":"publish","type":"post","link":"https:\/\/theark.ch\/fr\/news\/techno-pole-de-sierre-visite-de-la-cite-interdite-1008\/","title":{"rendered":"Techno-P\u00f4le de Sierre : Visite de La Cit\u00e9 interdite"},"content":{"rendered":"<p><a href=\"http:\/\/blog.theark.ch\/files\/2011\/09\/technoark.jpg\"><strong><\/strong><\/a><strong>Qu&rsquo;est-ce qui se trame r\u00e9ellement \u00e0 l&rsquo;int\u00e9rieur des b\u00e2timents du <a href=\"http:\/\/www.techno-pole.ch\" target=\"_blank\" rel=\"noopener\">Techno-P\u00f4le<\/a>? Quelles activit\u00e9s d\u00e9veloppent les entreprises qui y sont install\u00e9es?<\/strong><\/p>\n<p>Ces interrogations seront en partie lev\u00e9es ce vendredi 16 septembre, puisque le parc technologique situ\u00e9 sur les bords du Rh\u00f4ne\u00a0\u00e0 Sierre, ouvre ses portes au grand public. \u00abL&rsquo;objectif est de faire conna\u00eetre les infrastructures et l&rsquo;incroyable richesse de comp\u00e9tences r\u00e9unies sur le site.\u00a0Les Sierrois connaissent son existence, mais sans savoir ce qui s&rsquo;y passe. Pour eux, c&rsquo;est un peu la Cit\u00e9 interdite\u00bb, image Laurent Borella, responsable ex\u00e9cutif du Techno-P\u00f4le.<\/p>\n<p>Aujourd&rsquo;hui, avec ses 430 emplois \u00e0 haute valeur ajout\u00e9e et ses 60 PME, instituts et start-up, le parc informatique et scientifique est devenu un atout majeur dans la promotion \u00e9conomique de la ville de Sierre.<\/p>\n<p>Informatique, internet des objets, m\u00e9dias, ing\u00e9nierie, services, recherche et d\u00e9veloppement, les domaines d&rsquo;activit\u00e9s sont \u00e9tendus. Et contrairement \u00e0 une id\u00e9e re\u00e7ue, le roulement des entreprises, s&rsquo;il existe notamment pour les start-up, demeure faible. \u00abOn trouve sur le site des soci\u00e9t\u00e9s qui ont pignon sur rue depuis des ann\u00e9es comme Membratec, TI-Informatique ou Novelis. Le site rayonne en Suisse et m\u00eame en Europe \u00bb, rel\u00e8ve Laurent Borella.<\/p>\n<p><a href=\"http:\/\/blog.theark.ch\/files\/2011\/09\/Technop\u00f4le_NF_15.09.11.pdf\" target=\"_blank\" rel=\"noopener\">Suite de l\u2019article sur Le Nouvelliste \u2013 15.09.11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;est-ce qui se trame r\u00e9ellement \u00e0 l&rsquo;int\u00e9rieur des b\u00e2timents du Techno-P\u00f4le? Quelles activit\u00e9s d\u00e9veloppent les entreprises qui y sont install\u00e9es? Ces interrogations seront en partie lev\u00e9es ce vendredi 16 septembre, puisque le parc technologique situ\u00e9 sur les bords du Rh\u00f4ne\u00a0\u00e0 Sierre, ouvre ses portes au grand public. \u00abL&rsquo;objectif est de faire conna\u00eetre les infrastructures et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[186],"tags":[],"class_list":["post-12873","post","type-post","status-publish","format-standard","hentry","category-digital"],"acf":[],"_links":{"self":[{"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/posts\/12873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/comments?post=12873"}],"version-history":[{"count":0,"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/posts\/12873\/revisions"}],"wp:attachment":[{"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/media?parent=12873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/categories?post=12873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theark.ch\/fr\/wp-json\/wp\/v2\/tags?post=12873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}